{"id":995,"date":"2019-11-11T16:24:44","date_gmt":"2019-11-11T16:24:44","guid":{"rendered":"https:\/\/www.edicionesplatea.com\/blog\/?p=995"},"modified":"2025-02-19T07:55:57","modified_gmt":"2025-02-19T07:55:57","slug":"juegos-de-guerra-de-la-operacion-de-midway-arrogancia-o-autoengano","status":"publish","type":"post","link":"https:\/\/www.edicionesplatea.com\/blog\/juegos-de-guerra-de-la-operacion-de-midway-arrogancia-o-autoengano\/","title":{"rendered":"Juegos de guerra de la Operaci\u00f3n de Midway &#8211; \u00bfArrogancia o autoenga\u00f1o?"},"content":{"rendered":"\n<p>Salvo el estado mayor del Cuartel General de la Flota Combinada, todos los que participaban en los juegos de guerra estaban fascinados ante un programa tan formidable, que parec\u00eda un sue\u00f1o con mucha m\u00e1s imaginaci\u00f3n que consideraci\u00f3n por la realidad. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1001\" height=\"741\" src=\"https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2019\/11\/Midway-Mitsuo-Fuchida-Ediciones-Salamina-juegos-de-guerra.jpg\" alt=\"\" class=\"wp-image-996\" style=\"width:611px;height:451px\" srcset=\"https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2019\/11\/Midway-Mitsuo-Fuchida-Ediciones-Salamina-juegos-de-guerra.jpg 1001w, https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2019\/11\/Midway-Mitsuo-Fuchida-Ediciones-Salamina-juegos-de-guerra-300x222.jpg 300w, https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2019\/11\/Midway-Mitsuo-Fuchida-Ediciones-Salamina-juegos-de-guerra-768x569.jpg 768w\" sizes=\"auto, (max-width: 1001px) 100vw, 1001px\" \/><\/figure>\n<\/div>\n\n\n<p>M\u00e1s fascinante a\u00fan resultaba el modo en que se ejecutaba cada operaci\u00f3n en los juegos, sin la menor dificultad, desde la invasi\u00f3n de Midway y las Aleutianas hasta el asalto a Johnston y Haw\u00e1i. Ello se deb\u00eda, en no poca medida, a la arbitraria conducci\u00f3n del contraalmirante Ugaki, presidente de los juegos, que interven\u00eda con frecuencia para anular decisiones de los \u00e1rbitros.<\/p>\n\n\n\n<p>En las maniobras de tablero, por ejemplo, se desarroll\u00f3 una situaci\u00f3n en la que el grupo Nagumo se tuvo que enfrentar a un bombardeo por parte de aviones enemigos basados en tierra mientras sus propios aparatos bombardeaban Midway. De acuerdo con las reglas, el capit\u00e1n de corbeta Okumiya, oficial de estado mayor de la 4.\u00aa Divisi\u00f3n de Portaaviones y \u00e1rbitro en los juegos, lanz\u00f3 el dado para determinar el resultado del bombardeo y resolvi\u00f3 que el enemigo hab\u00eda conseguido nueve impactos sobre los portaaviones japoneses.<\/p>\n\n\n\n<p>El Akagi y el Kaga se anotaron como hundidos. Sin embargo, el almirante Ugaki redujo arbitrariamente el n\u00famero de impactos enemigos a s\u00f3lo tres, que a\u00fan fueron suficientes para hundir al Kaga, pero que s\u00f3lo dejaba al Akagi ligeramente da\u00f1ado. Para sorpresa de Okumiya, incluso esa resoluci\u00f3n revisada fue subsiguientemente cancelada y el Kaga reapareci\u00f3 como participante en la siguiente fase de los juegos, cubriendo las invasiones de Nueva Caledonia y las islas Fiyi. <\/p>\n\n\n\n<p>Los veredictos de los \u00e1rbitros en relaci\u00f3n a los resultados del combate a\u00e9reo se ama\u00f1aron de forma similar, siempre a favor de las fuerzas japonesas.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/edicionessalamina.com\/p\/midway-mitsuo-fuchida\">QUIERO EL LIBRO<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salvo el estado mayor del Cuartel General de la Flota Combinada, todos los que participaban en los juegos de guerra estaban fascinados ante un programa tan formidable, que parec\u00eda un sue\u00f1o con mucha m\u00e1s imaginaci\u00f3n que consideraci\u00f3n por la realidad. &hellip; <a href=\"https:\/\/www.edicionesplatea.com\/blog\/juegos-de-guerra-de-la-operacion-de-midway-arrogancia-o-autoengano\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[422],"tags":[233,432,431,430],"class_list":["post-995","post","type-post","status-publish","format-standard","hentry","category-midway-la-batalla-que-condeno-a-japon","tag-233","tag-flota-combinada","tag-ugaki","tag-yamamoto"],"_links":{"self":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/comments?post=995"}],"version-history":[{"count":3,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/995\/revisions"}],"predecessor-version":[{"id":2485,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/995\/revisions\/2485"}],"wp:attachment":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/media?parent=995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/categories?post=995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/tags?post=995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}