{"id":423,"date":"2017-10-06T15:54:14","date_gmt":"2017-10-06T15:54:14","guid":{"rendered":"http:\/\/www.edicionesplatea.com\/blog\/?p=423"},"modified":"2025-02-12T11:57:41","modified_gmt":"2025-02-12T11:57:41","slug":"islas-terceiras-batalla-de-san-miguel-ya-a-la-venta","status":"publish","type":"post","link":"https:\/\/www.edicionesplatea.com\/blog\/islas-terceiras-batalla-de-san-miguel-ya-a-la-venta\/","title":{"rendered":"Islas Terceiras &#8211; Batalla de San Miguel. \u00a1Ya a la venta!"},"content":{"rendered":"\n<p>\u00a1Ya disponible!<br> Islas Terceiras: La batalla naval de San Miguel. Operaciones navales espa\u00f1olas del siglo XVI, 1581-82. Antonio Luis G\u00f3mez Beltr\u00e1n\u200b<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"http:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2017\/10\/Tr\u00edptico-Islas-Terceiras-Batalla-de-San-Miguel-Ediciones-Salamina.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"843\" height=\"403\" src=\"http:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2017\/10\/Tr\u00edptico-Islas-Terceiras-Batalla-de-San-Miguel-Ediciones-Salamina.jpg\" alt=\"\" class=\"wp-image-424\" srcset=\"https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2017\/10\/Tr\u00edptico-Islas-Terceiras-Batalla-de-San-Miguel-Ediciones-Salamina.jpg 843w, https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2017\/10\/Tr\u00edptico-Islas-Terceiras-Batalla-de-San-Miguel-Ediciones-Salamina-300x143.jpg 300w, https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2017\/10\/Tr\u00edptico-Islas-Terceiras-Batalla-de-San-Miguel-Ediciones-Salamina-768x367.jpg 768w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Un estudio in\u00e9dito y en profundidad de una de las batallas navales m\u00e1s importantes del siglo XVI con Don \u00c1lvaro de Baz\u00e1n al frente. Todos los que lo hab\u00e9is precomprado empezar\u00e9is a recibirlo a partir de la pr\u00f3xima semana.<br> <br> Colecci\u00f3n Salamina Series Naval<br> Tama\u00f1o: 15\u00d723 cm.<br> N\u00ba de p\u00e1ginas: 418<br> Incluye 46 p\u00e1ginas con mapas y croquis de batallas a todo color<br> Incluye un tr\u00edptico a todo color 40&#215;23 cm desplegable<br> Encuadernaci\u00f3n: Tapa blanda con solapas<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/edicionessalamina.com\/p\/la-batalla-naval-de-san-miguel-antonio-luis-gomez-beltran\">QUIERO EL LIBRO<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ya disponible! Islas Terceiras: La batalla naval de San Miguel. Operaciones navales espa\u00f1olas del siglo XVI, 1581-82. Antonio Luis G\u00f3mez Beltr\u00e1n\u200b Un estudio in\u00e9dito y en profundidad de una de las batallas navales m\u00e1s importantes del siglo XVI con Don &hellip; <a href=\"https:\/\/www.edicionesplatea.com\/blog\/islas-terceiras-batalla-de-san-miguel-ya-a-la-venta\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166],"tags":[168,172,173,47],"class_list":["post-423","post","type-post","status-publish","format-standard","hentry","category-islas-terceiras-batalla-de-san-miguel","tag-alvaro-de-bazan","tag-batalla-de-san-miguel","tag-islas-terceiras","tag-tercios"],"_links":{"self":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/comments?post=423"}],"version-history":[{"count":2,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/423\/revisions"}],"predecessor-version":[{"id":2355,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/423\/revisions\/2355"}],"wp:attachment":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/media?parent=423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/categories?post=423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/tags?post=423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}