{"id":1151,"date":"2020-04-14T15:50:34","date_gmt":"2020-04-14T15:50:34","guid":{"rendered":"https:\/\/www.edicionesplatea.com\/blog\/?p=1151"},"modified":"2025-02-19T08:10:29","modified_gmt":"2025-02-19T08:10:29","slug":"la-decisiva-campana-de-orbetello-1646-capitulo-4-el-leon-contra-la-jauria-vol-ii","status":"publish","type":"post","link":"https:\/\/www.edicionesplatea.com\/blog\/la-decisiva-campana-de-orbetello-1646-capitulo-4-el-leon-contra-la-jauria-vol-ii\/","title":{"rendered":"La decisiva campa\u00f1a de Orbetello (1646). Cap\u00edtulo 4. El le\u00f3n contra la jaur\u00eda Vol. II"},"content":{"rendered":"\n<p>Ante el estancamiento en Catalu\u00f1a, en Francia se ide\u00f3 abrir un nuevo frente de lucha en un lugar inesperado, que proporcionara un \u00e9xito rotundo y a poca costa, que levantara su moral y hundiera la de sus enemigos.<\/p>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"1024\" src=\"https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2020\/04\/El-leo\u0301n-contra-la-jauri\u0301a-vol-II-Ediciones-Salamina-2-646x1024.png\" alt=\"\" class=\"wp-image-1154\" srcset=\"https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2020\/04\/El-leo\u0301n-contra-la-jauri\u0301a-vol-II-Ediciones-Salamina-2-646x1024.png 646w, https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2020\/04\/El-leo\u0301n-contra-la-jauri\u0301a-vol-II-Ediciones-Salamina-2-189x300.png 189w, https:\/\/www.edicionesplatea.com\/blog\/wp-content\/uploads\/2020\/04\/El-leo\u0301n-contra-la-jauri\u0301a-vol-II-Ediciones-Salamina-2.png 681w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/figure>\n<\/div>\n\n\n<p>El objetivo fijado eran los \u00abpresidios\u00bb espa\u00f1oles en la costa italiana de Toscana, y para ello se prepar\u00f3 una gran expedici\u00f3n: La flota, al mando nuevamente de Brez\u00e9, zarp\u00f3 de Tol\u00f3n el 26 de abril de 1646, con el vicealmirante Daugnon y el jefe de escuadra Montigny como mandos subordinados. Constaba de 16 buques de combate, 4 urcas, 8 brulotes, 20 galeras y nada menos que 68 buques menores (tartanas, polacras y dem\u00e1s) para transportar el cuerpo de desembarco, de unos 5.000 infantes y 500 jinetes al mando del pr\u00edncipe Tom\u00e1s de Saboya, que no mucho antes era general al servicio de Felipe IV. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Por supuesto con el correspondiente tren de asedio, municiones y provisiones de toda \u00edndole. El 9 de mayo fondeaban frente a su objetivo, tomando r\u00e1pidamente los peque\u00f1os fortines de Santo Stefano y de Telam\u00f3n, con menos de 100 defensores, pero resistiendo el mayor de Orbetello, pese a no disponer sino de 200 defensores. Hubo que desembarcar la artiller\u00eda y el material de asedio, cosa que se efectu\u00f3 el 14 de mayo, pero los trabajos avanzaron lentamente, provocando las iras del impaciente Mazarino. <\/p>\n\n\n\n<p>La plaza la defend\u00edan los 200 soldados espa\u00f1oles e italianos mencionados, al mando de un gran capit\u00e1n de N\u00e1poles, D. Carlos de la Gatta, quien recibi\u00f3 alg\u00fan socorro urgente enviado por el virrey de N\u00e1poles, conducido audazmente nada menos que por un Baz\u00e1n, el nieto del gran D. \u00c1lvaro, en sus galeras. Pero el 21 qued\u00f3 circunvalada por entero la plaza y tales auxilios ya eran imposibles. En Espa\u00f1a la noticia del ataque lleg\u00f3 pronto, organiz\u00e1ndose a toda prisa una armada de socorro, reuni\u00e9ndose una flota de 22 veleros, entre galeones, urcas y fragatas, mas cuatro brulotes y unas 30 galeras, entre las de las escuadras de Espa\u00f1a, N\u00e1poles, Sicilia, Cerde\u00f1a y G\u00e9nova. Correspondi\u00f3 el mando supremo al Conde de Linares, por ser el Capit\u00e1n General de ellas y tener lugar la campa\u00f1a en el Mediter\u00e1neo.<\/p>\n\n\n\n<p>El 12 de junio avistaron la isla del Giglio, tomando por sorpresa a las falucas de vigilancia del enemigo, que lev\u00f3 anclas y se dirigi\u00f3 hacia la espa\u00f1ola. La formaci\u00f3n francesa alternaba veleros y galeras, la espa\u00f1ola con los veleros en vanguardia en l\u00ednea de frente y las galeras detr\u00e1s, seguidas de 8 veleros rezagados. Soplaba un terral muy flojo, lo que daba el barlovento a los franceses, pero pronto calm\u00f3 en la ma\u00f1ana del 14 de junio, a eso de las nueve. Unos y otros remolcaron a sus veleros con las galeras, con ventaja espa\u00f1ola por tener m\u00e1s de ellas que buques, navegando paralelamente, hasta que el viento se aviv\u00f3, soplando ahora del mar y con ventaja para los espa\u00f1oles, que se encontraron a barlovento y se dirigieron hacia la flota enemiga, que se bati\u00f3 en retirada.<\/p>\n\n\n\n<p>Pero pronto se cerraron las distancias y comenz\u00f3 el combate, con la caracter\u00edstica formaci\u00f3n en creciente de los espa\u00f1oles y los franceses con su escuadra dividida en tres divisiones, cada una de seis buques: y una disposici\u00f3n similar, con una reserva de seis nav\u00edos detr\u00e1s. La vanguardia la mandaba Daugnon en el gale\u00f3n \u00abLa Lune\u00bb, el centro Brez\u00e9 en el gran \u00abSaint Louis\u00bb, la retaguardia Montigny en el \u00abSoley\u00bb y la reserva Montade. En cuanto a las galeras de uno y otro bando se situaron por detr\u00e1s de los veleros, atentas a cualquier imprevisto, pero incapaces de participar en un combate en l\u00ednea entre galeones.<\/p>\n\n\n\n<p>Tras cuatro horas de incesante ca\u00f1oneo, una fragata espa\u00f1ola, la \u00abSanta Catalina\u00bb, qued\u00f3 aislada y amenazada por varios enemigos, por lo que su capit\u00e1n orden\u00f3 darle fuego y abandonarla con su dotaci\u00f3n para evitar que fuera apresada. Pero en l\u00edneas generales la formaci\u00f3n espa\u00f1ola iba venciendo a la francesa amenazando con encerrarla contra la costa, dando ya la victoria por segura. Sin embargo, ocurri\u00f3 entonces que la capitana espa\u00f1ola perdi\u00f3 su trinquete por el fuego enemigo, que al caer desaparej\u00f3 la vela mayor. Temiendo fuera blanco de los brulotes enemigos, las galeras se acercaron a darla un remolque y la confusi\u00f3n se apoder\u00f3 de la l\u00ednea espa\u00f1ola, lo que permiti\u00f3 a la escuadra francesa retirarse con las primeras horas de oscuridad. Aparte de serias bajas y aver\u00edas en ambas partes, los franceses hab\u00edan lanzado un brulote que se consumi\u00f3 sin hacer da\u00f1o.<\/p>\n\n\n\n<p>Las fuentes francesas cuentan una historia muy distinta: ellos iban venciendo hasta que un ca\u00f1onazo espa\u00f1ol mat\u00f3 a Brez\u00e9 en la popa de su buque insignia, pr\u00e1cticamente parti\u00e9ndolo en dos, lo que hizo que Daugnon, ahora al mando, se desmoralizase y ordenara la retirada. No parece que ese fuera el caso: con las comunicaciones entre buques de la \u00e9poca y en medio de un gran y confuso combate, envuelto en el humo de los ca\u00f1onazos y fuego de mosquetes, era casi imposible que la muerte del almirante franc\u00e9s se conociera r\u00e1pidamente, y que ella decidiera el curso de la batalla que ellos estiman victoriosa hasta entonces. <\/p>\n\n\n\n<p>Y es de recordar otros casos notorios en que tal acontecimiento no tuvo esas consecuencias, como el mism\u00edsimo de Nelson en Trafalgar. Mientras, las fuentes espa\u00f1olas insisten en que si la victoria no se complet\u00f3, fue por las rivalidades y poco entendimiento mutuo entre los jefes espa\u00f1oles, cosa que parece mucho m\u00e1s factible a la vista de los acontecimientos posteriores. Al d\u00eda siguiente se divis\u00f3 a la escuadra francesa a cosa de 12 millas a barlovento, sin intenci\u00f3n alguna de reanudar ese combate que presuntamente les hab\u00eda sido favorable y vengar a su almirante. La espa\u00f1ola, con su capitana ya reparada, hizo rumbo a Porto Ercole, para evitar que la enemiga cubriera su cabeza de playa frente a Orbetello. Cambi\u00f3 el viento, y al tener barlovento la espa\u00f1ola, la enemiga simplemente se retir\u00f3 a mayor distancia.<\/p>\n\n\n\n<p>El 16 a la anochecida, salt\u00f3 un temporal del SE, que hizo que los franceses volvieran a sus puertos y comprometi\u00f3 a las galeras de uno y otro bando. Una de las espa\u00f1olas, la \u00abSanta B\u00e1rbara\u00bb, se fue contra la costa, ahog\u00e1ndose 46 forzados, pero tambi\u00e9n lo fue una de las francesas, capturando las espa\u00f1olas su dotaci\u00f3n, artiller\u00eda y pertrechos cuando calm\u00f3 el temporal. Aquello dio pi\u00e9 a un peque\u00f1o combate entre unas y otras galeras, de lo que result\u00f3 apresada otra francesa, con lo que se reemplaz\u00f3 la perdida. Tambi\u00e9n a un brulote, separado de su escuadra.<\/p>\n\n\n\n<p>Ante la retirada de la escuadra francesa, y no sin muchas discusiones entre los mandos espa\u00f1oles, se decidi\u00f3 socorrer al comprometido Orbetello, gracias a nuevos refuerzos por mar llegados en ocho buques de N\u00e1poles, que se unieron el 25. Por fin, desembarcaron de las dotaciones de la escuadra 3.300 soldados, al mando de su almirante o segundo jefe, Pimienta, que divididos en dos cuerpos atacaron al enemigo, reembarcando tras seis horas de combate. Un nuevo refuerzo de N\u00e1poles, llegado en peque\u00f1os costeros, de 4.000 hombres, decidi\u00f3 la cuesti\u00f3n, junto con la llegada de seis buques de C\u00e1diz con provisiones.<\/p>\n\n\n\n<p>La suerte ya estaba echada, y Tom\u00e1s de Saboya se retir\u00f3 precipitadamente con su caballer\u00eda a sus posesiones, dejando desamparada su infanter\u00eda, que escap\u00f3 como pudo (gracias en parte a algunos buques franceses que actuaron de noche) perdiendo toda su artiller\u00eda: 20 ca\u00f1ones y un gran mortero, as\u00ed como sus trenes de bagajes y provisiones, en total desbandada. A las p\u00e9rdidas francesas se unieron las alrededor de 70 falucas, tartanas, etc., utilizadas como exploradoras y como embarcaciones anfibias, siendo unas apresadas y otras quemadas por los vencedores.<\/p>\n\n\n\n<p>Como en la 2\u00aa batalla naval de Tarragona, la de Orbetello supuso el fin del l\u00edder naval del momento, primero de Sourdis, a quien se priv\u00f3 del mando, y ahora de Brez\u00e9, por muerte en combate. Y si bien es cierto que el arzobispo de Burdeos no brill\u00f3 especialmente al mando de sus escuadras, pese a triunfos como el de Guetaria, no lo es menos que con Brez\u00e9 el liderazgo, aunque hab\u00eda mejorado mucho, no ofreci\u00f3 resultados realmente espectaculares, ni ante C\u00e1diz ni ante Barcelona, seg\u00fan hemos visto. Tenemos la impresi\u00f3n de que la historiograf\u00eda francesa ha valorado y alabado en exceso a un almirante que no logr\u00f3 los \u00e9xitos esperables a su superioridad de medios y al estado de sus enemigos. Pero era el primer almirante de val\u00eda de la nueva marina gala, y eso pesa, como tambi\u00e9n que muriera con 27 a\u00f1os, cuando a\u00fan pod\u00eda haber aprendido y madurado mucho.<\/p>\n\n\n\n<p>Pero hubo m\u00e1s: desde entonces y hasta el fin de la guerra, las escuadras francesas se limitaron a incursiones por sorpresa, amagos y poco m\u00e1s, rehuyendo siempre un combate directo, y perdi\u00e9ndolo en las pocas ocasiones en que no pudieron evitarlo. As\u00ed, y aunque las p\u00e9rdidas navales francesas de la campa\u00f1a no fueron importantes, la falta de un adecuado l\u00edder naval, unida indudablemente a otras causas de las que luego hablaremos, hicieron que el papel de la \u00abMarine Royale\u00bb durante los 13 a\u00f1os que a\u00fan dur\u00f3 la guerra, fuera realmente decepcionante para la inversi\u00f3n en todos los sentidos que se hab\u00eda volcado en su creaci\u00f3n desde los tiempos de Richelieu.<\/p>\n\n\n\n<p>Por ello, y pese a la ausencia de una batalla aplastante por sus resultados t\u00e1cticos, lo cierto es que Orbetello fue una campa\u00f1a decisiva, cuesti\u00f3n que pese a lo que parezca, es m\u00e1s com\u00fan en la Historia Naval de lo esperable a primera vista. El que no se obtuviera un \u00e9xito verdaderamente aplastante (como sucedi\u00f3 tambi\u00e9n en la 2\u00aa de Tarragona) fue muy mal digerido en toda Espa\u00f1a y sus dominios, pues se estim\u00f3 que se hab\u00eda perdido una ocasi\u00f3n verdaderamente \u201cdorada\u201d para propinar un dur\u00edsimo golpe al poder naval franc\u00e9s. Y ahora estaba muy claro que las disensiones, rivalidades y celos entre los jefes espa\u00f1oles fueron decisivas en la responsabilidad de que el \u00e9xito no fuera todo lo grande que se deseaba, y mas en una situaci\u00f3n tan cr\u00edtica. <\/p>\n\n\n\n<p>Pero esa suele ser tambi\u00e9n la consecuencia de que una contienda se alargue demasiado: la moral no solo baja en la tropa y mariner\u00eda, tambi\u00e9n en los mandos. Incluso Felipe IV estaba m\u00e1s que enojado y orden\u00f3 detener y enjuiciar a los mandos, empezando por el mismo Conde de Linares (o Linhares, pues era portugu\u00e9s, lo que dio mucho que hablar), al almirante Pimienta, al marqu\u00e9s de Bayona, a D. Pablo de Contreras e incluso al III Marqu\u00e9s de El Viso, nieto del gran Baz\u00e1n. Como se dijo ya en tiempos de Olivares, lo m\u00e1s preocupante no era ya la falta de medios de todas las clases, sino la \u00abfalta de cabezas\u00bb.<\/p>\n\n\n\n<p>Y para poner un poco de orden en las fuerzas navales de la monarqu\u00eda hisp\u00e1nica, al rey no se le ocurri\u00f3 mas que hacer gobernador general de todas ellas a su hijo bastardo, a D. Juan Jos\u00e9 de Austria (habido con una simple c\u00f3mica o actriz). Aquella parec\u00eda la proverbial segunda parte que tanto desmerece de la primera, recordando al gran D. Juan de Austria de Lepanto, pero lo cierto es que el nuevo jefe devolvi\u00f3 la tan necesaria moral a la fuerza y se condujo de forma bastante acertada.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.edicionesplatea.com\/blog\/category\/el-leon-contra-la-jauria-vol-ii\/\">EL LE\u00d3N CONTRA LA JAUR\u00cdA VOL. II. Batallas y campa\u00f1as navales espa\u00f1olas, 1640-1700<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante el estancamiento en Catalu\u00f1a, en Francia se ide\u00f3 abrir un nuevo frente de lucha en un lugar inesperado, que proporcionara un \u00e9xito rotundo y a poca costa, que levantara su moral y hundiera la de sus enemigos. El objetivo &hellip; <a href=\"https:\/\/www.edicionesplatea.com\/blog\/la-decisiva-campana-de-orbetello-1646-capitulo-4-el-leon-contra-la-jauria-vol-ii\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[444],"tags":[485,454,484,451,47],"class_list":["post-1151","post","type-post","status-publish","format-standard","hentry","category-el-leon-contra-la-jauria-vol-ii","tag-485","tag-armada-espanola","tag-orbetello","tag-siglo-xvii","tag-tercios"],"_links":{"self":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":4,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"predecessor-version":[{"id":2506,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/posts\/1151\/revisions\/2506"}],"wp:attachment":[{"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edicionesplatea.com\/blog\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}